{"id":3859,"date":"2019-12-03T06:00:15","date_gmt":"2019-12-03T11:00:15","guid":{"rendered":"http:\/\/www.carrefourfgafp.com\/SEC\/?p=3859"},"modified":"2021-06-17T16:37:42","modified_gmt":"2021-06-17T20:37:42","slug":"970-378","status":"publish","type":"post","link":"https:\/\/www.carrefourfgafp.com\/SEC\/2019\/12\/03\/970-378\/","title":{"rendered":"Site d\u00e9di\u00e9 au trouble du d\u00e9ficit de l&rsquo;attention avec ou sans hyperactivit\u00e9 (TDAH), cr\u00e9\u00e9 et \u00e9labor\u00e9 sous la coordination de Dr Annick Vincent, m\u00e9decin-psychiatre."},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text]Source informative et de r\u00e9f\u00e9rences pour tous, grand public et professionnels. Contient entre autres, outils de d\u00e9pistage, d\u2019\u00e9valuation et de suivi, trucs et astuces pour mieux \u00ab\u00a0vivre avec le TDAH\u00a0\u00bb, suggestions de livres et vid\u00e9os, liste de ressources.[\/vc_column_text][vc_separator type=\u00a0\u00bbtransparent\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb]<a href=\"http:\/\/www.attentiondeficit-info.com\/\" target=\"_blank\"  class=\"qbutton  qbutton_with_icon\" style=\"\">Lire l'article sur le site http:\/\/www.attentiondeficit-info.com\/<i class=\"button_icon  fa fa-link\" style=\"\"><\/i><\/a>[vc_separator type=\u00a0\u00bbtransparent\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb][vc_separator type=\u00a0\u00bbtransparent\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb][vc_separator type=\u00a0\u00bbtransparent\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text]Source informative et de r\u00e9f\u00e9rences pour tous, grand public et professionnels. Contient entre autres, outils de d\u00e9pistage, d\u2019\u00e9valuation et de suivi, trucs et astuces pour mieux \u00ab\u00a0vivre avec le TDAH\u00a0\u00bb, suggestions de livres et vid\u00e9os, liste de ressources.[\/vc_column_text][vc_separator type=\u00a0\u00bbtransparent\u00a0\u00bb border_style=\u00a0\u00bb\u00a0\u00bb][vc_separator&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[8,44,100],"_links":{"self":[{"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/posts\/3859"}],"collection":[{"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/comments?post=3859"}],"version-history":[{"count":2,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/posts\/3859\/revisions"}],"predecessor-version":[{"id":3868,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/posts\/3859\/revisions\/3868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/media\/3866"}],"wp:attachment":[{"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/media?parent=3859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/categories?post=3859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carrefourfgafp.com\/SEC\/wp-json\/wp\/v2\/tags?post=3859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}